{"id":33,"date":"2013-09-20T19:30:00","date_gmt":"2013-09-20T19:30:00","guid":{"rendered":"http:\/\/esferas.org\/msqlu\/2013\/09\/20\/openwrt-cuando-se-rompe\/"},"modified":"2013-09-20T19:30:00","modified_gmt":"2013-09-20T19:30:00","slug":"openwrt-cuando-se-rompe","status":"publish","type":"post","link":"https:\/\/esferas.org\/msqlu\/2013\/09\/20\/openwrt-cuando-se-rompe\/","title":{"rendered":"OpenWrt: cuando se rompe &#8230;"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" alt=\"Imagen miniatura para no_hope_Wireless_access_point.png\" src=\"https:\/\/esferas.org\/mt\/msqlu\/assets_c\/2013\/09\/no_hope_Wireless_access_point-miniatura-autox107-56.png\" class=\"mt-image-left\" style=\"float: left; margin: 0 20px 20px 0;\" height=\"107\" width=\"100\" \/>&#8230; lo hace de verdad. Menos mal que tiene un arreglo sencillo, porque lo de hoy ha sido de traca.<\/p>\n<\/p>\n<p><!--more--><\/p>\n<p>Esta ma\u00f1ana termin\u00e9 de instalar el nuevo servidor que va a funcionar como UDC (Unidad De Comunicaciones) y estaba casi listo para comenzar la configuraci\u00f3n del cortafuegos cuando he recibido una llamada de los hom\u00ednidos con los que trabajo: la impresi\u00f3n en color <em>no va<\/em>. P\u00e1nico y gritos por doquier (y es que hoy el jefe se ha dado el lujo de venir cabreado al trabajo) y mucha urgencia porque ten\u00edan que imprimir unos cat\u00e1logos para envi\u00e1rselos a potenciales clientes.<\/p>\n<p>Bien. El caso es que es buscando la soluci\u00f3n del problema he visto que estaban enviando tal volumen gr\u00e1fico a la impresora que el servidor estaba colapsado. La m\u00e1quina es una fotocopiadora Canon con unos controladores bastante asquerosos y casi todo el trabajo de conversi\u00f3n lo realiza CUPS. Ya les he dicho que no es necesario que el folleto de dos p\u00e1ginas ocupe 15 Mb para verlo por pantalla o para imprimirlo en papel normalucho pero &#8230;<\/p>\n<p>Hace tiempo que ten\u00eda previsto cambiar el servidor de impresi\u00f3n a una m\u00e1quina nueva y he pensado que pod\u00eda aprovechar la ocasi\u00f3n para hacerlo ahora; el antiguo lleva Debian 6 y el nuevo Debian 7, algo ten\u00eda ya ganado.\u00a0 Adem\u00e1s, as\u00ed me pon\u00eda yo tambi\u00e9n en plan apocal\u00edptico y les pod\u00eda decir que es imprescindible detener todo el <strong>subsistema de impresi\u00f3n<\/strong> para arreglar la aver\u00eda. Atentos al detalle: es necesario hablar de subsistemas y no de programas o servidores. Subsistemas suena a algo grande, complejo, incluso industrial. Es casi m\u00edstico y es perfecto para que entiendan que es <strong>grave.<\/strong><\/p>\n<p>Vale. Software instalado y configuraci\u00f3n de las impresoras traspasada. No ve\u00eda problemas a la vista.\u00a0 (\u00a1 Je ! \u00a1 Qu\u00e9 no ve\u00eda problemas, dice !)<\/p>\n<p>La primera en la frente. Pero de verdad. Utilizo el panel de control del enrutador (y servidor de nombres principal) que funciona con OpenWRT (de ah\u00ed el t\u00edtulo de la entrada) y procedo a cambiar la IP del antiguo servidor por la del nuevo. Siempre he considerado pr\u00e1ctico, aunque la red sea peque\u00f1a, que existan nombres de tercer nivel para definir servicios. Facilita mucho la migraci\u00f3n y el balanceo de carga.<\/p>\n<p>Como no he visto ninguna advertencia ni ning\u00fan mensaje de error tampoco he comprobado que la IP hab\u00eda cambiado. Y no, tras un buen rato de aplicar el algoritmo del mono (y de estrellarme a base de bien) no me ha dado por comprobar si ocurr\u00eda algo raro en el <em>router<\/em>. He tenido que entrar por SSH para averiguar que no hab\u00eda espacio en disco. He buscado algo que borrar, he intentado editar a mano la configuraci\u00f3n, he probado a copiarla y enlazarla a otro sistema de archivos y nada. En algunos casos daba la operaci\u00f3n por buena pero no la realizaba, en otros indicaba que el disco estaba lleno y en otros incluso he visto fallos de segmentaci\u00f3n. Una juerga.<\/p>\n<p>As\u00ed que he buscado por la red y he encontrado <a href=\"https:\/\/forum.openwrt.org\/viewtopic.php?id=24969\">un hilo<\/a> donde comentan qu\u00e9 se puede hacer y <a href=\"https:\/\/forum.openwrt.org\/viewtopic.php?id=38244\">otro<\/a> donde explican por qu\u00e9 se ha producido eso. Al parecer no se pueden borrar archivos en el sistema <a href=\"https:\/\/es.wikipedia.org\/wiki\/SquashFS\">squashfs<\/a> (obviamente porque est\u00e1 sobre una ROM) y la capa que superponen para usarlo normalmente es una <a href=\"https:\/\/es.wikipedia.org\/wiki\/JFFS2\">jffs2<\/a> que almacena todos los cambios realizados sobre la inferior como metadatos: si ya falta espacio borrar archivos o directorios significa consumir m\u00e1s espacio en jffs2.<\/p>\n<p>El segundo hilo que menciono en el p\u00e1rrafo anterior comenta justamente la misma situaci\u00f3n en la que me he encontrado. Trat\u00e9 de instalar un punto de acceso de una VPN y el sistema fall\u00f3 miserablemente por falta de espacio. Lo dej\u00e9 as\u00ed porque el enrutador segu\u00eda enrutando normalmente (aunque ten\u00eda sus parones de cuando en cuando) y porque pens\u00e9 que el sistema eliminar\u00eda los archivos descargados y las instalaciones parciales (malamente acostumbrado a Debian). Pues no. Tras varios reinicios un tanto desperados he entrado en el panel de control y he hecho lo siguiente para recuperar tanto el espacio como chisme funcionando:<\/p>\n<ol>\n<li>Descargar una copia de seguridad en el disco\u00a0<\/li>\n<li>Reiniciar a valores de f\u00e1brica empleando el mismo interfaz web<\/li>\n<li>Conectar un port\u00e1til al router despu\u00e9s del reinicio para:\n<ol>\n<li>Recibir una IP con los valores originales<\/li>\n<li>Acceder de nuevo al panel de control<\/li>\n<li>Restaurar tambi\u00e9n desde all\u00ed la configuraci\u00f3n que antes hab\u00eda salvado.<\/li>\n<\/ol>\n<\/li>\n<li>Y a gozar &#8230;<\/li>\n<\/ol>\n<p>&#8230; hasta que ponga en marcha el nuevo UDC que espero poder terminar ma\u00f1ana.<\/p>\n<h3>Sobre el ambiente de hoy en el trabajo<\/h3>\n<p>No hay comunicaci\u00f3n entre los cuatro gatos que somos en la empresa. A m\u00ed, el \u00fanico inform\u00e1tico, se dirigen siempre con las peticiones elevadas a la categor\u00eda <em>vamos-a-morir-todos.\u00a0<\/em> Supongo que se habr\u00e1n percatado de que cuanto m\u00e1s me presionan, antes cedo para hacer la chapuza de turno y menos tiempo dedico a investigar el origen del problema. \u00bf Qu\u00e9 m\u00e1s da si se volver\u00e1 a presentar m\u00e1s adelante si seguimos en marcha ahora ?<\/p>\n<p>Y esto me recuerda algo que he estado rumiando bastante desde hace un tiempo: \u00bf puede alguien al que le pagan una peque\u00f1a fortuna por dirigir una empresa permitirse hundir la moral de todo el equipo de la misma sin dar explicaciones ? \u00bf La templanza no deber\u00eda estar impl\u00edcita en el cargo ? Porque dar \u00f3rdenes y lanzar exigencias locas lo hace cualquiera, pero dirigir es algo m\u00e1s. Que el personal te odie o no es indiferente. Conseguir que pierdan toda empat\u00eda con la empresa y su trabajo ya no. Lo del liderazgo es, sobre todo, saber que el <em>l\u00edder<\/em> est\u00e1 dentro del equipo con una tarea muy definida. Y que no es un se\u00f1or feudal. \u00bf No ?<\/p>\n<\/p>\n<p><span hidden class=\"__iawmlf-post-loop-links\" data-iawmlf-links=\"[{&quot;id&quot;:1431,&quot;href&quot;:&quot;https:\\\/\\\/forum.openwrt.org\\\/viewtopic.php?id=24969&quot;,&quot;archived_href&quot;:&quot;&quot;,&quot;redirect_href&quot;:&quot;https:\\\/\\\/forum.archive.openwrt.org\\\/viewtopic.php?id=24969&quot;,&quot;checks&quot;:[],&quot;broken&quot;:false,&quot;last_checked&quot;:null,&quot;process&quot;:&quot;done&quot;},{&quot;id&quot;:1432,&quot;href&quot;:&quot;https:\\\/\\\/forum.openwrt.org\\\/viewtopic.php?id=38244&quot;,&quot;archived_href&quot;:&quot;&quot;,&quot;redirect_href&quot;:&quot;https:\\\/\\\/forum.archive.openwrt.org\\\/viewtopic.php?id=38244&quot;,&quot;checks&quot;:[],&quot;broken&quot;:false,&quot;last_checked&quot;:null,&quot;process&quot;:&quot;done&quot;},{&quot;id&quot;:1433,&quot;href&quot;:&quot;https:\\\/\\\/es.wikipedia.org\\\/wiki\\\/SquashFS&quot;,&quot;archived_href&quot;:&quot;https:\\\/\\\/web-wp.archive.org\\\/web\\\/20260415220904\\\/https:\\\/\\\/es.wikipedia.org\\\/wiki\\\/SquashFS&quot;,&quot;redirect_href&quot;:&quot;&quot;,&quot;checks&quot;:[{&quot;date&quot;:&quot;2026-05-13 13:36:59&quot;,&quot;http_code&quot;:429},{&quot;date&quot;:&quot;2026-05-22 16:41:21&quot;,&quot;http_code&quot;:429},{&quot;date&quot;:&quot;2026-06-07 06:16:02&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-06-11 09:37:30&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-06-14 22:34:29&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-06-30 07:45:24&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-07-23 17:00:59&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-07-29 15:53:40&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-08-02 04:58:53&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-08-10 15:40:18&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-08-16 09:09:36&quot;,&quot;http_code&quot;:200}],&quot;broken&quot;:false,&quot;last_checked&quot;:{&quot;date&quot;:&quot;2026-08-16 09:09:36&quot;,&quot;http_code&quot;:200},&quot;process&quot;:&quot;done&quot;},{&quot;id&quot;:1434,&quot;href&quot;:&quot;https:\\\/\\\/es.wikipedia.org\\\/wiki\\\/JFFS2&quot;,&quot;archived_href&quot;:&quot;&quot;,&quot;redirect_href&quot;:&quot;&quot;,&quot;checks&quot;:[],&quot;broken&quot;:false,&quot;last_checked&quot;:null,&quot;process&quot;:&quot;done&quot;}]\"><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>&#8230; lo hace de verdad. Menos mal que tiene un arreglo sencillo, porque lo de hoy ha sido de traca.<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"1","sticky":false,"template":"","format":"standard","meta":{"_import_markdown_pro_load_document_selector":0,"_import_markdown_pro_submit_text_textarea":"","webmentions_disabled_pings":false,"webmentions_disabled":false,"footnotes":""},"categories":[5],"tags":[59,52,60,54],"class_list":["post-33","post","type-post","status-publish","format-standard","hentry","category-hardware","tag-hominidos","tag-mi-lugar-de-trabajo","tag-openwrt","tag-udc"],"_links":{"self":[{"href":"https:\/\/esferas.org\/msqlu\/wp-json\/wp\/v2\/posts\/33","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/esferas.org\/msqlu\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/esferas.org\/msqlu\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/esferas.org\/msqlu\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/esferas.org\/msqlu\/wp-json\/wp\/v2\/comments?post=33"}],"version-history":[{"count":0,"href":"https:\/\/esferas.org\/msqlu\/wp-json\/wp\/v2\/posts\/33\/revisions"}],"wp:attachment":[{"href":"https:\/\/esferas.org\/msqlu\/wp-json\/wp\/v2\/media?parent=33"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/esferas.org\/msqlu\/wp-json\/wp\/v2\/categories?post=33"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/esferas.org\/msqlu\/wp-json\/wp\/v2\/tags?post=33"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}