{"id":412,"date":"2010-07-29T09:50:11","date_gmt":"2010-07-29T09:50:11","guid":{"rendered":"http:\/\/esferas.org\/msqlu\/2010\/07\/29\/microblogs\/"},"modified":"2010-07-29T09:50:11","modified_gmt":"2010-07-29T09:50:11","slug":"microblogs","status":"publish","type":"post","link":"https:\/\/esferas.org\/msqlu\/2010\/07\/29\/microblogs\/","title":{"rendered":"Microblogs"},"content":{"rendered":"<p><img decoding=\"async\" src=\"\/dotclear\/public\/Logos\/identica-logo.png\" alt=\"identi.ca\" title=\"identi.ca, Jul 2010\" \/><\/p>\n<p>\u00bf Para qu\u00e9 sirve ? \u00bf Es otra <em>moda<\/em> como <a href=\"http:\/\/www.facebook.com\">facebook<\/a> ? En \u00e9ste \u00faltimo tuve cuenta pero lo dej\u00e9 porque me parec\u00eda tambi\u00e9n muy intrusivo; casi como una secta.<\/p>\n<p><!--more--><\/p>\n<p>El caso es que tengo una cuenta en <a href=\"http:\/\/identi.ca\/victormoral\">identi.ca<\/a> por aquello de probarlo (siendo adem\u00e1s la versi\u00f3n <em>abierta<\/em> de Twitter) y no le he visto la gracia por ninguna parte.<\/p>\n<p>Vamos, no es que diga que no sirva, es que este blog representa una v\u00e1lvula de escape con la que adem\u00e1s mantengo informadas a ciertas personas, me divierto y me ense\u00f1a algunas cosas. Ahora aprenderme un nuevo entorno y un nuevo lenguaje, para estar limitados a unas cuantas palabras &#8230; no s\u00e9 &#8230; si es que tampoco tengo tanto que decir. En cualquier caso debo echarle un vistazo m\u00e1s a fondo porque dado el ruido que genera el invento lo mismo hasta le encuentro utilidad.<\/p>\n<p>Y es curioso, porque  acabo de volver a echarle un vistazo a lo que tengo publicado y me he encontrado con el enlace de una escalera liviana en la que estuve interesado. Pues dado que existe un buen n\u00famero de formas de enviar informaci\u00f3n lo mismo hasta me vale &#8230;<\/p>\n<p>Tengo que sopesarlo.<\/p>\n<p><span hidden class=\"__iawmlf-post-loop-links\" data-iawmlf-links=\"[{&quot;id&quot;:1760,&quot;href&quot;:&quot;http:\\\/\\\/www.facebook.com&quot;,&quot;archived_href&quot;:&quot;https:\\\/\\\/web-wp.archive.org\\\/web\\\/20260415154057\\\/https:\\\/\\\/www.facebook.com\\\/&quot;,&quot;redirect_href&quot;:&quot;&quot;,&quot;checks&quot;:[{&quot;date&quot;:&quot;2026-04-26 15:14:57&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-05-09 21:02:46&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-05-23 17:33:50&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-06-07 11:54:36&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-06-12 08:49:16&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-06-19 07:51:02&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-06-27 17:01:58&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-06-30 18:16:56&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-07-08 00:44:57&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-07-11 09:46:13&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-07-15 23:32:13&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-07-24 14:45:33&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-07-29 04:35:37&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-08-03 10:55:14&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-08-07 18:10:15&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-08-22 18:17:02&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-08-27 21:46:51&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-09-02 08:55:16&quot;,&quot;http_code&quot;:400}],&quot;broken&quot;:false,&quot;last_checked&quot;:{&quot;date&quot;:&quot;2026-09-02 08:55:16&quot;,&quot;http_code&quot;:400},&quot;process&quot;:&quot;done&quot;},{&quot;id&quot;:1761,&quot;href&quot;:&quot;http:\\\/\\\/identi.ca\\\/victormoral&quot;,&quot;archived_href&quot;:&quot;&quot;,&quot;redirect_href&quot;:&quot;&quot;,&quot;checks&quot;:[],&quot;broken&quot;:false,&quot;last_checked&quot;:null,&quot;process&quot;:&quot;done&quot;}]\"><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00bf Para qu\u00e9 sirve ? \u00bf Es otra moda como facebook ? En \u00e9ste \u00faltimo tuve cuenta pero lo dej\u00e9 porque me parec\u00eda tambi\u00e9n muy intrusivo; casi como una secta.<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_import_markdown_pro_load_document_selector":0,"_import_markdown_pro_submit_text_textarea":"","webmentions_disabled_pings":false,"webmentions_disabled":false,"footnotes":""},"categories":[207],"tags":[309,44],"class_list":["post-412","post","type-post","status-publish","format-standard","hentry","category-proyectos","tag-identi-ca","tag-servicios-web"],"_links":{"self":[{"href":"https:\/\/esferas.org\/msqlu\/wp-json\/wp\/v2\/posts\/412","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/esferas.org\/msqlu\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/esferas.org\/msqlu\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/esferas.org\/msqlu\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/esferas.org\/msqlu\/wp-json\/wp\/v2\/comments?post=412"}],"version-history":[{"count":0,"href":"https:\/\/esferas.org\/msqlu\/wp-json\/wp\/v2\/posts\/412\/revisions"}],"wp:attachment":[{"href":"https:\/\/esferas.org\/msqlu\/wp-json\/wp\/v2\/media?parent=412"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/esferas.org\/msqlu\/wp-json\/wp\/v2\/categories?post=412"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/esferas.org\/msqlu\/wp-json\/wp\/v2\/tags?post=412"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}