{"id":4379,"date":"2023-01-28T13:18:27","date_gmt":"2023-01-28T12:18:27","guid":{"rendered":"https:\/\/esferas.org\/msqlu\/?p=4379"},"modified":"2023-01-28T13:18:28","modified_gmt":"2023-01-28T12:18:28","slug":"100daysofhomelab-dia-1-algo-con-wordpress-y-algo-con-nextcloud","status":"publish","type":"post","link":"https:\/\/esferas.org\/msqlu\/2023\/01\/28\/100daysofhomelab-dia-1-algo-con-wordpress-y-algo-con-nextcloud\/","title":{"rendered":"100DaysOfHomeLab: d\u00eda 1 &#8211; algo con wordpress y algo con nextcloud"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Comienzo diciendo que para m\u00ed los servidores en Internet que tengo alquilados son parte de mi <em>laboratorio casero<\/em> por lo que cualquier cosa que haga con ellos cuenta para \u00e9sto. <\/p>\n<span hidden class=\"__iawmlf-post-loop-links\" data-iawmlf-links=\"[{&quot;id&quot;:71,&quot;href&quot;:&quot;https:\\\/\\\/apps.nextcloud.com\\\/apps\\\/cookbook&quot;,&quot;archived_href&quot;:&quot;https:\\\/\\\/web-wp.archive.org\\\/web\\\/20260415095351\\\/https:\\\/\\\/apps.nextcloud.com\\\/apps\\\/cookbook&quot;,&quot;redirect_href&quot;:&quot;&quot;,&quot;checks&quot;:[{&quot;date&quot;:&quot;2026-04-27 18:37:37&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-05-02 05:52:56&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-05-08 03:31:30&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-05-16 14:34:16&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-05-30 23:44:26&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-06-06 08:23:46&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-07-29 17:28:11&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-08-31 22:08:25&quot;,&quot;http_code&quot;:200}],&quot;broken&quot;:false,&quot;last_checked&quot;:{&quot;date&quot;:&quot;2026-08-31 22:08:25&quot;,&quot;http_code&quot;:200},&quot;process&quot;:&quot;done&quot;},{&quot;id&quot;:72,&quot;href&quot;:&quot;https:\\\/\\\/f-droid.org\\\/es\\\/packages\\\/com.nextcloud_cookbook_flutter&quot;,&quot;archived_href&quot;:&quot;&quot;,&quot;redirect_href&quot;:&quot;&quot;,&quot;checks&quot;:[],&quot;broken&quot;:false,&quot;last_checked&quot;:null,&quot;process&quot;:&quot;done&quot;}]\"><\/span>\n\n\n<!--more-->\n\n\n\n<h3 class=\"wp-block-heading\">Nuevo blog en WordPress<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">A petici\u00f3n de mi amigo Luismi (antiguo compa\u00f1ero de trabajo) he creado una nueva instalaci\u00f3n de WordPress para que su hijo pueda emplearlo para publicar sus rutas camperas. Como siempre digo, mientras la instalaci\u00f3n no me acarree gastos no tengo problema alguno. En el caso de que por alguna raz\u00f3n lo haga pues o me ayudan con el servidor o se van a otro. Y tanto Luismi como Susana est\u00e1n de acuerdo en ello desde el principio. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Lo primero que ha hecho Luismi ha sido comprar el dominio con la misma velocidad y el mismo impulso de siempre. Seg\u00fan le dije que s\u00ed a lo de instalarlo en mi servidor se lanz\u00f3 a comprarlo y en muy poco me hab\u00eda puesto a m\u00ed como contacto t\u00e9cnico. As\u00ed puedo gestionar el DNS y obtener certificados electr\u00f3nicos con facilidad. <\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Recetas en Nextcloud <\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Nextcloud tiene una aplicaci\u00f3n de recetas de cocina llamada <a rel=\"noreferrer noopener\" href=\"https:\/\/apps.nextcloud.com\/apps\/cookbook\" target=\"_blank\">cookbook<\/a> que no tiene mal aspecto. El funcionamiento tambi\u00e9n est\u00e1 bien pensado y es \u00e1gil de utilizar. Hasta ahora las recetas las he metido en un blog con acceso parcialmente p\u00fablico debido a que mi suegra, quien me dio bastantes recetas, no ha querido nunca que estuviesen al alcance de los dem\u00e1s. Supongo porque lo considera algo muy familiar y no le apetece que extra\u00f1os le echen la vista encima. Yo lo he respetado y las he tenido siempre as\u00ed: unas privadas que precisan autorizaci\u00f3n y otras no. Tambi\u00e9n, y dado que las recetas me vienen mejor en papel, tuve que a\u00f1adir un complemento extra a WordPress para poder imprimirlas todas. Funciona bien pero hay algo que me chirr\u00eda. Quiz\u00e1s sea que no he empleado ning\u00fan tipo especial de entrada o ning\u00fan complemento pero no. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">As\u00ed que he estado pensando que quiz\u00e1s nextcloud pudiera echarme una mano. Es algo que empleo a diario y parece que tiene una <a href=\"https:\/\/f-droid.org\/es\/packages\/com.nextcloud_cookbook_flutter\/\">aplicaci\u00f3n para m\u00f3vil <\/a>que funciona muy bien. Como existe la opci\u00f3n de imprimir las recetas y a\u00f1adirles im\u00e1genes, categor\u00edas y etiquetas pues me viene de perlas. He instalado ambas y las he probado y de maravilla. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Comienzo diciendo que para m\u00ed los servidores en Internet que tengo alquilados son parte de mi laboratorio casero por lo que cualquier cosa que haga con ellos cuenta para \u00e9sto.<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_import_markdown_pro_load_document_selector":0,"_import_markdown_pro_submit_text_textarea":"","webmentions_disabled_pings":false,"webmentions_disabled":false,"footnotes":""},"categories":[1207],"tags":[15,705,1208,451],"class_list":["post-4379","post","type-post","status-publish","format-standard","hentry","category-100daysofhomelab","tag-blog","tag-nextcloud","tag-recetas-de-cocina","tag-wordpress"],"_links":{"self":[{"href":"https:\/\/esferas.org\/msqlu\/wp-json\/wp\/v2\/posts\/4379","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/esferas.org\/msqlu\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/esferas.org\/msqlu\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/esferas.org\/msqlu\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/esferas.org\/msqlu\/wp-json\/wp\/v2\/comments?post=4379"}],"version-history":[{"count":4,"href":"https:\/\/esferas.org\/msqlu\/wp-json\/wp\/v2\/posts\/4379\/revisions"}],"predecessor-version":[{"id":4386,"href":"https:\/\/esferas.org\/msqlu\/wp-json\/wp\/v2\/posts\/4379\/revisions\/4386"}],"wp:attachment":[{"href":"https:\/\/esferas.org\/msqlu\/wp-json\/wp\/v2\/media?parent=4379"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/esferas.org\/msqlu\/wp-json\/wp\/v2\/categories?post=4379"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/esferas.org\/msqlu\/wp-json\/wp\/v2\/tags?post=4379"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}